{"id":58338,"date":"2026-08-28T09:39:00","date_gmt":"2026-08-28T07:39:00","guid":{"rendered":"https:\/\/ide-code.zonadetest.es\/products\/ref_01874\/"},"modified":"2026-08-28T09:39:00","modified_gmt":"2026-08-28T07:39:00","slug":"01874-es","status":"publish","type":"ide_variant","link":"https:\/\/ide-code.zonadetest.es\/es\/productos\/bases-y-clavijas-industriales\/bases-y-clavijas-para-baja-tension-ip67\/ref_01874\/","title":{"rendered":"01874"},"content":{"rendered":"<p>Base mural IP66 &#8211; IP67 2P+T 100\/130V 125A 4H<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Base mural IP66 &#8211; IP67 2P+T 100\/130V 125A 4H<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","ide_category":[66938],"ide_product":[69054],"ide_application":[67138],"class_list":["post-58338","ide_variant","type-ide_variant","status-publish","hentry","ide_category-bases-y-clavijas-para-baja-tension-ip67","ide_product-pp-mund-bm67-es","ide_application-conexion-electrica"],"acf":[],"_links":{"self":[{"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/ide_variant\/58338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/ide_variant"}],"about":[{"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/types\/ide_variant"}],"wp:attachment":[{"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/media?parent=58338"}],"wp:term":[{"taxonomy":"ide_category","embeddable":true,"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/ide_category?post=58338"},{"taxonomy":"ide_product","embeddable":true,"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/ide_product?post=58338"},{"taxonomy":"ide_application","embeddable":true,"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/ide_application?post=58338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}