{"id":62666,"date":"2026-08-28T09:39:57","date_gmt":"2026-08-28T07:39:57","guid":{"rendered":"https:\/\/ide-code.zonadetest.es\/products\/ref_05322\/"},"modified":"2026-08-28T09:39:57","modified_gmt":"2026-08-28T07:39:57","slug":"05322-es","status":"publish","type":"ide_variant","link":"https:\/\/ide-code.zonadetest.es\/es\/productos\/bases-y-clavijas-industriales\/bases-y-clavijas-para-baja-tension-ip44\/ref_05322\/","title":{"rendered":"05322"},"content":{"rendered":"<p>Base mural IP44 3P+T 480\/500V 16A 7H<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Base mural IP44 3P+T 480\/500V 16A 7H<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","ide_category":[66934],"ide_product":[69050],"ide_application":[67138],"class_list":["post-62666","ide_variant","type-ide_variant","status-publish","hentry","ide_category-bases-y-clavijas-para-baja-tension-ip44","ide_product-pp-mund-bm44-es","ide_application-conexion-electrica"],"acf":[],"_links":{"self":[{"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/ide_variant\/62666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/ide_variant"}],"about":[{"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/types\/ide_variant"}],"wp:attachment":[{"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/media?parent=62666"}],"wp:term":[{"taxonomy":"ide_category","embeddable":true,"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/ide_category?post=62666"},{"taxonomy":"ide_product","embeddable":true,"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/ide_product?post=62666"},{"taxonomy":"ide_application","embeddable":true,"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/ide_application?post=62666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}