{"id":64652,"date":"2026-08-28T09:40:26","date_gmt":"2026-08-28T07:40:26","guid":{"rendered":"https:\/\/ide-code.zonadetest.es\/products\/ref_07803\/"},"modified":"2026-08-28T09:40:26","modified_gmt":"2026-08-28T07:40:26","slug":"07803-es","status":"publish","type":"ide_variant","link":"https:\/\/ide-code.zonadetest.es\/es\/productos\/bases-y-clavijas-industriales\/bases-y-clavijas-para-baja-tension-ip67\/ref_07803\/","title":{"rendered":"07803"},"content":{"rendered":"<p>Base empotrar inclinada IP66 &#8211; IP67 3P+N+T >50V(301-500HZ) 16A 2H<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Base empotrar inclinada IP66 &#8211; IP67 3P+N+T >50V(301-500HZ) 16A 2H<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","ide_category":[66938],"ide_product":[69026],"ide_application":[67138],"class_list":["post-64652","ide_variant","type-ide_variant","status-publish","hentry","ide_category-bases-y-clavijas-para-baja-tension-ip67","ide_product-pp-mund-bei67-es","ide_application-conexion-electrica"],"acf":[],"_links":{"self":[{"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/ide_variant\/64652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/ide_variant"}],"about":[{"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/types\/ide_variant"}],"wp:attachment":[{"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/media?parent=64652"}],"wp:term":[{"taxonomy":"ide_category","embeddable":true,"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/ide_category?post=64652"},{"taxonomy":"ide_product","embeddable":true,"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/ide_product?post=64652"},{"taxonomy":"ide_application","embeddable":true,"href":"https:\/\/ide-code.zonadetest.es\/es\/wp-json\/wp\/v2\/ide_application?post=64652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}